{"id":863,"date":"2024-04-10T15:51:16","date_gmt":"2024-04-10T15:51:16","guid":{"rendered":"https:\/\/castelogreen.com\/?p=863"},"modified":"2024-04-10T16:21:52","modified_gmt":"2024-04-10T16:21:52","slug":"offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit","status":"publish","type":"post","link":"https:\/\/castelogreen.com\/pt\/offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit\/","title":{"rendered":"Oferta e integra\u00e7\u00e3o: Retorno da cria\u00e7\u00e3o de rela\u00e7\u00f5es s\u00f3lidas durante o recrutamento"},"content":{"rendered":"<h2>Introdu\u00e7\u00e3o<\/h2>\n<p><span style=\"font-weight: 400;\">Em artigos anteriores, abordei a primeira e a segunda fases do processo de recrutamento: <\/span><a href=\"https:\/\/castelogreen.com\/pt\/sourcing-and-screening-building-relationships-as-you-recruit\/\"><span style=\"font-weight: 400;\">sele\u00e7\u00e3o de fontes e triagem<\/span><\/a><span style=\"font-weight: 400;\"> e <\/span><a href=\"https:\/\/castelogreen.com\/pt\/interviews-reinforcinging-relationships-as-you-recruit\/\"><span style=\"font-weight: 400;\">entrevista<\/span><\/a><span style=\"font-weight: 400;\">. A fase final consiste em transformar todo este esfor\u00e7o naquilo que realmente se pretende: um novo membro da equipa produtivo - atrav\u00e9s de uma oferta bem sucedida e de uma integra\u00e7\u00e3o eficaz.\u00a0<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Etapa 8: Oferta\u00a0<\/span><\/h2>\n<h3><span style=\"font-weight: 400;\">Expectativas definidas<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u00c9 aqui que se espera realmente come\u00e7ar a obter o retorno do seu investimento num processo de recrutamento mais rico e baseado em rela\u00e7\u00f5es. Esperamos obter uma taxa de sucesso de 75%+ quando chegamos ao fecho. Temos uma boa rela\u00e7\u00e3o com o candidato, fomos diretos com ele ao longo de todo o processo, ele compreende as condi\u00e7\u00f5es prov\u00e1veis de um pacote de compensa\u00e7\u00e3o, qual ser\u00e1 o seu papel, como ser\u00e1 apoiado, que experi\u00eancia poder\u00e1 adquirir, quem ser\u00e1 o seu diretor e at\u00e9 quais ser\u00e3o algumas das dificuldades que ter\u00e1 de enfrentar.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De um modo geral, esperamos que tenham conseguido tra\u00e7ar um quadro preciso do que poder\u00e1 ser o seu futuro, trabalhando para a minha equipa.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">O valor de um quadro de carreira<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Esta abordagem implica que tenha definido um quadro de carreira para a sua equipa, com categorias profissionais, escal\u00f5es salariais e uma progress\u00e3o clara na carreira. Este pode n\u00e3o ser o caso se a sua empresa ainda for pequena e estiver a crescer. Talvez saiba que \u00e9 importante, mas \u00e9 apenas uma de uma longa lista de tarefas a realizar pela dire\u00e7\u00e3o de engenharia e pelos RH. Mas \u00e9 importante.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se tiver defini\u00e7\u00f5es de fun\u00e7\u00f5es e n\u00edveis salariais claros (mesmo que bastante amplos), o candidato ter\u00e1 mais confian\u00e7a em si, na prov\u00e1vel justi\u00e7a da sua remunera\u00e7\u00e3o e voc\u00ea ter\u00e1 mais confian\u00e7a para negociar o sal\u00e1rio que considera correto. Construir um quadro completo de desenvolvimento de carreira com defini\u00e7\u00f5es de fun\u00e7\u00f5es, matrizes de compet\u00eancias, processos de promo\u00e7\u00e3o, processos de revis\u00e3o salarial, etc., leva tempo. Mas ter um primeiro esbo\u00e7o das faixas salariais para as fun\u00e7\u00f5es-chave n\u00e3o \u00e9 assim t\u00e3o dif\u00edcil e vale bem a pena.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">A oferta<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">N\u00e3o estragues tudo nesta altura. N\u00e3o se enerve com o dinheiro. Continue a tratar o candidato com respeito, como um igual numa negocia\u00e7\u00e3o. Saiba o que pode pagar e o quanto valoriza o candidato. Nesta altura, o candidato j\u00e1 deve ter uma faixa salarial na cabe\u00e7a - partilhada com a descri\u00e7\u00e3o do cargo\/an\u00fancio e discutida brevemente no in\u00edcio do processo. A \u00fanica margem para discord\u00e2ncia deve ser o facto de concordarem com a posi\u00e7\u00e3o do candidato na faixa salarial comunicada - inferior, m\u00e9dia, superior?\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O trabalho do gestor de contrata\u00e7\u00e3o \u00e9 saber onde acredita que o candidato se situa no intervalo e ter uma raz\u00e3o para o apoiar.\u00a0<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Negocia\u00e7\u00e3o<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Esteja preparado para que o candidato discorde de si e saiba como tenciona responder - ou seja, como se fosse um dos dois,\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Respeito a sua perspetiva, mas este \u00e9 o n\u00edvel salarial que consideramos correto devido a X, Y, Z\".\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ou<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0Ou\u00e7o o seu ponto de vista e estou disposto a encontr\u00e1-lo no meio, porque parece que ambos concordamos que seria \u00f3timo t\u00ea-lo na equipa e seria uma pena n\u00e3o encontrar uma forma de o fazer funcionar\".\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Permitam-me que desafie a ortodoxia do controlo or\u00e7amental que faz todo o sentido em grandes organiza\u00e7\u00f5es com grandes encargos salariais. Com uma pequena equipa de engenheiros, tenho tend\u00eancia para seguir uma filosofia de n\u00e3o me preocupar com as pequenas coisas. Uma diferen\u00e7a de alguns milhares de euros no n\u00edvel salarial n\u00e3o vai ser o fator decisivo para o sucesso ou o fracasso de uma empresa jovem. O retorno do investimento de um engenheiro de software talentoso deve ser muito superior ao custo total da sua contrata\u00e7\u00e3o. Uma boa contrata\u00e7\u00e3o de um membro motivado da equipa pode ser transformadora para uma equipa mais pequena.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, cada organiza\u00e7\u00e3o tem uma cultura diferente em rela\u00e7\u00e3o \u00e0 negocia\u00e7\u00e3o e a consist\u00eancia interna \u00e9 importante (e justa para os outros membros da equipa e candidatos). Mas n\u00e3o permita que o seu Dr. Jekyll se transforme no Sr. Hyde. Se vai jogar duro no final do processo, talvez seja melhor poupar algum tempo de constru\u00e7\u00e3o de rela\u00e7\u00f5es mais cedo - porque est\u00e1 prestes a corroer grande parte da boa vontade obtida.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Etapa 9: Pr\u00e9-jun\u00e7\u00e3o<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Esta \u00e9 uma parte do processo frequentemente esquecida. Talvez porque muito do pensamento e da discuss\u00e3o sobre a ind\u00fastria de software venha dos EUA, onde os per\u00edodos de aviso pr\u00e9vio de duas semanas s\u00e3o a norma. N\u00e3o h\u00e1 muito tempo para as coisas acontecerem. Na Europa, por outro lado, \u00e9 frequente encontrar engenheiros de software com um per\u00edodo de pr\u00e9-aviso de 2 ou 3 meses para trabalhar. \u00c9 muito tempo para que os acontecimentos da vida se interponham no caminho de uma transi\u00e7\u00e3o suave.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Portanto... se est\u00e1 \u00e0 espera 4, 8 ou 12 semanas que o seu novo membro da equipa apare\u00e7a, precisa de ter um plano para se manter em contacto com ele. Isto \u00e9 ligeiro e simples, pois na maioria das vezes nada acontece. No entanto, h\u00e1 algumas coisas que pode fazer e que podem ajudar a garantir que n\u00e3o perde ningu\u00e9m entre a oferta e a chegada - acontece... eu fiz isso uma vez. Tamb\u00e9m pode ajudar a garantir que a etapa seguinte - a integra\u00e7\u00e3o - seja t\u00e3o eficaz quanto poss\u00edvel:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Envie-lhes um e-mail ou uma mensagem de WhatsApp a cada 2-3 semanas para se certificar de que est\u00e1 tudo bem com eles<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Planeie a sua integra\u00e7\u00e3o e informe-os do que vai acontecer - n\u00e3o precisa de deixar isto para o \u00faltimo minuto<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Analisar as necessidades t\u00e9cnicas - est\u00e1 a comprar equipamento, a dar-lhes um subs\u00eddio para equipamento, a enviar-lhes alguma coisa? Fale antecipadamente sobre as suas necessidades, de acordo com as limita\u00e7\u00f5es da sua atividade, e prepare o equipamento atempadamente (de prefer\u00eancia, pouco antes do dia 1)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Podem perguntar se h\u00e1 trabalho preparat\u00f3rio a fazer - eu n\u00e3o sugeriria nada para al\u00e9m de ganharem familiaridade com elementos da pilha tecnol\u00f3gica que s\u00e3o novos para eles... nem sequer encorajaria isso... mas as novas contrata\u00e7\u00f5es s\u00e3o normalmente entusiastas e talvez estejam a terminar o seu antigo emprego, pelo que querem dedicar o seu tempo de \"passatempo\" a algo que possa ser \u00fatil no novo emprego<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">N\u00e3o se sinta tentado a falar de projectos, a dar acesso a reposit\u00f3rios, a envolv\u00ea-los em discuss\u00f5es sobre arquitetura - eles ainda n\u00e3o trabalham para si - envie o sinal de que respeita os limites e espera que eles tamb\u00e9m sejam disciplinados a este respeito<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Siga estes passos e estar\u00e1 bem preparado para a chegada do novo contratado e para a \u00faltima tarefa importante - a integra\u00e7\u00e3o.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Etapa 10: Integra\u00e7\u00e3o<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Colhe-se o que se semeia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Os dividendos come\u00e7am realmente a aparecer assim que o membro da equipa rec\u00e9m-selecionado inicia a sua integra\u00e7\u00e3o. Mas primeiro... e se a sua propaganda de vendas no processo de recrutamento fosse apenas isso - propaganda? Uma fic\u00e7\u00e3o envernizada e perfeita para o Insta.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Est\u00e1s prestes a ser descoberto.\u00a0<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Inautenticidade durante a integra\u00e7\u00e3o<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Ao longo destes artigos, falamos de autenticidade. \u00c9 muito mais importante ser aut\u00eantico, verdadeiro, honesto do que meramente \"atrativo\". Lembre-se, todas as empresas t\u00eam desafios, stress e disfun\u00e7\u00f5es. Todas as empresas t\u00eam personalidades, pol\u00edticas e press\u00f5es interessantes. Os candidatos sabem disso. Eles querem saber o que <\/span><span style=\"font-weight: 400;\">seu<\/span><span style=\"font-weight: 400;\"> O sabor do stress \u00e9 para que possam garantir melhor a compatibilidade com os seus problemas pessoais, fraquezas e factores de frustra\u00e7\u00e3o. \u00c9 claro que quer fazer o mesmo.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">H\u00e1 uma raz\u00e3o para fazermos sempre uma variante da pergunta \"o que \u00e9 que realmente o irrita\" nas entrevistas comportamentais. Um candidato detesta ser mantido no escuro, sem saber como as decis\u00f5es s\u00e3o tomadas, e anseia por mais intera\u00e7\u00e3o com a empresa em geral. O candidato seguinte detesta reuni\u00f5es, distrac\u00e7\u00f5es e \"coisas da empresa\" e s\u00f3 quer que o deixem entrar no fluxo e produzir software. Qualquer uma destas duas caricaturas pode n\u00e3o ser adequada \u00e0 sua equipa e \u00e0 sua cultura.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">N\u00e3o se fala muito em trabalho de equipa, colabora\u00e7\u00e3o e apoio m\u00fatuo quando a norma \u00e9 marcar pontos nos pedidos pull, os pile-ons do Slack s\u00e3o considerados um bom desporto quando algu\u00e9m faz asneira ou os membros da equipa s\u00e3o encorajados a trabalhar sozinhos, a concentrarem-se no seu pr\u00f3prio trabalho e a n\u00e3o interromperem outros que possam estar \"em fluxo\".<\/span><\/p>\n<p><span style=\"font-weight: 400;\">N\u00e3o apregoe a urg\u00eancia, a velocidade e a cad\u00eancia de lan\u00e7amentos se a sua realidade s\u00e3o reuni\u00f5es intermin\u00e1veis, decis\u00f5es por comit\u00e9 e um pipeline CI\/CD que os anos 90 pediram para ser devolvido.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">N\u00e3o pregue a obsess\u00e3o pelo cliente se a sua equipa de produtos nunca fala com os clientes, se estes raramente falam consigo (a n\u00e3o ser atrav\u00e9s de um roteiro e de um documento de atraso), se n\u00e3o faz ideia de como o seu produto \u00e9 realmente utilizado ou se est\u00e1 afogado em bugs e pedidos de apoio abertos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">N\u00e3o se vanglorie da sua excel\u00eancia t\u00e9cnica se a d\u00edvida t\u00e9cnica estiver fora de controlo, se n\u00e3o tiver um processo para tomar decis\u00f5es de arquitetura e design ou se tiver uma mentalidade esot\u00e9rica de \"apenas constru\u00e7\u00e3o\" para todos os componentes - principais ou n\u00e3o.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ser\u00e1s descoberto.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O novo membro da equipa sentir-se-\u00e1 enganado. Poder\u00e1 n\u00e3o ficar muito tempo (e normalmente s\u00e3o os bons elementos que se v\u00e3o embora mais depressa). E se ficarem, a sua motiva\u00e7\u00e3o ser\u00e1 menor e precisar\u00e1 de ser reabilitada - uma perda de produtividade e uma perda de tempo para a dire\u00e7\u00e3o.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Planear a integra\u00e7\u00e3o<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Partindo do princ\u00edpio de que n\u00e3o cometeu nenhum destes erros - e, como erros, ter\u00e3o sido cometidos logo no in\u00edcio do processo de recrutamento -, ent\u00e3o a integra\u00e7\u00e3o deve ser simples. Sim, simples, mas ainda h\u00e1 tempo para fazer asneiras.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">D\u00ea ao processo de integra\u00e7\u00e3o o tempo e a aten\u00e7\u00e3o que merece. D\u00ea ao novo membro da equipa um companheiro - n\u00e3o confie no chefe de equipa para fazer todo o trabalho de indu\u00e7\u00e3o. Ter pontos de contacto estruturados. Eu tenho uma abordagem do dia 1, da semana 1, do m\u00eas 1 quando estou num papel de lideran\u00e7a. Obviamente, v\u00e1rias vezes por dia para o colega, o chefe de equipa e os outros membros da equipa.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pense em tarefas de bootcamp, projectos iniciais, exposi\u00e7\u00e3o a diferentes partes da equipa e da pilha - o que for mais adequado para a sua equipa... mas seja intencional e explique o que est\u00e1 a pensar. Verifique regularmente - est\u00e1 a ir muito depressa, muito devagar? \u00c9 muito comum que o novo membro da equipa diga \"demasiado devagar\". Conseguir o equil\u00edbrio certo no caminho para o alto desempenho \u00e9 uma das artes do grande gestor.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">D\u00ea uma rea\u00e7\u00e3o franca - qualquer que seja o sabor necess\u00e1rio. Se tiver um processo formal de est\u00e1gio, \u00f3timo. Certifique-se de que o novo membro da equipa o compreende e de que o cumpre... todos n\u00f3s estamos ocupados. Coloque as etapas do est\u00e1gio no seu calend\u00e1rio e no do novo membro da equipa no dia 1.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Seja solid\u00e1rio<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Assumir que a integra\u00e7\u00e3o \u00e9 um processo dif\u00edcil para o novo membro da equipa e esperar que ele tenha alguns problemas. A minha ideia \u00e9 que a organiza\u00e7\u00e3o assumiu um compromisso com o candidato e o candidato assumiu um compromisso com a organiza\u00e7\u00e3o. Cabe a ambas as partes fazer com que o processo de integra\u00e7\u00e3o seja t\u00e3o bem sucedido quanto todos esperavam. Foi investido muito dinheiro quando um novo membro da equipa termina o seu per\u00edodo de est\u00e1gio. N\u00e3o desperdice esse investimento sendo r\u00e1pido a julgar.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">D\u00ea ao novo membro da equipa o mesmo cuidado, considera\u00e7\u00e3o e apoio que d\u00e1 ao membro mais antigo da sua equipa. As coisas podem come\u00e7ar mal por in\u00fameras raz\u00f5es e, muitas vezes, ningu\u00e9m investe o tempo necess\u00e1rio para as corrigir. H\u00e1 definitivamente algo na sabedoria convencional de que uma m\u00e1 contrata\u00e7\u00e3o nunca ir\u00e1 melhorar. Todos os gestores de longo prazo ter\u00e3o feito contrata\u00e7\u00f5es que rapidamente se aperceberam que eram m\u00e1s, mas \u00e9 igualmente poss\u00edvel que tenha feito uma m\u00e1 integra\u00e7\u00e3o.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Certifique-se de que envida todos os esfor\u00e7os para determinar se uma contrata\u00e7\u00e3o \u00e9 um erro ou se a preparou para falhar antes de decidir cortar as suas perdas.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Conclus\u00e3o<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Se conseguiu chegar at\u00e9 ao fim destes tr\u00eas artigos, espero que tenha aprendido algumas dicas e t\u00e9cnicas para tornar o seu processo de recrutamento mais bem sucedido. A contrata\u00e7\u00e3o \u00e9 uma das tarefas mais importantes para qualquer equipa em crescimento. Consome muito tempo, \u00e9 arriscado e incerto. A maioria das equipas, na maior parte das vezes, n\u00e3o atinge os seus objectivos de contrata\u00e7\u00e3o. Isto representa um custo significativo para qualquer empresa, mas especialmente para as que est\u00e3o a iniciar a sua fase de crescimento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adotar uma abordagem de constru\u00e7\u00e3o de rela\u00e7\u00f5es e aplic\u00e1-la de forma consistente ao longo de todo o processo de recrutamento ajud\u00e1-lo-\u00e1 a colher a mais valiosa das colheitas - uma contrata\u00e7\u00e3o de elevada qualidade. O candidato sabe no que se est\u00e1 a meter. Muitos membros da equipa j\u00e1 o conhecem. Sabe qual a melhor forma de o integrar. Ele sabe no que se deve concentrar. Come\u00e7am a trabalhar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Obt\u00e9m-se rapidamente um membro da equipa produtivo que se enquadra na sua cultura e que, esperamos, se baseie nos seus pontos fortes e que, em breve, indicar\u00e1 a sua rede de contactos para vir trabalhar consigo tamb\u00e9m.<\/span><\/p>\n<div class=\"elementor-element elementor-element-b496f62 elementor-widget elementor-widget-theme-post-content\" data-id=\"b496f62\" data-element_type=\"widget\" data-widget_type=\"theme-post-content.default\">\n<div class=\"elementor-widget-container\">\n<p>Para mais informa\u00e7\u00f5es e opini\u00f5es do Castelo Green, siga-nos em\u00a0<a href=\"https:\/\/www.linkedin.com\/company\/castelo-green\/\">LinkedIn<\/a>.<\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Introdu\u00e7\u00e3o Em artigos anteriores, abordei a primeira e a segunda fases do processo de recrutamento: procura, sele\u00e7\u00e3o e entrevista. A fase final consiste em transformar todo este esfor\u00e7o naquilo que realmente se pretende: um novo membro da equipa produtivo - atrav\u00e9s de uma oferta bem sucedida e de uma integra\u00e7\u00e3o eficaz.  Etapa 8: As expectativas da oferta s\u00e3o definidas [...]<\/p>","protected":false},"author":3,"featured_media":864,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Offer and Onboarding: Payback for Building Strong Relationships as you Recruit - Castelo Green<\/title>\n<meta name=\"description\" content=\"Offer and onboarding processes can further reinforce the relationship you build with new software engineering team members,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/castelogreen.com\/pt\/offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Offer and Onboarding: Payback for Building Strong Relationships as you Recruit - Castelo Green\" \/>\n<meta property=\"og:description\" content=\"Offer and onboarding processes can further reinforce the relationship you build with new software engineering team members,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/castelogreen.com\/pt\/offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit\/\" \/>\n<meta property=\"og:site_name\" content=\"Castelo Green\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-10T15:51:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-10T16:21:52+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/castelogreen.com\/wp-content\/uploads\/2024\/04\/onboarding-and-relationship-building.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Allen Shaw\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Allen Shaw\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/castelogreen.com\/offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit\/\",\"url\":\"https:\/\/castelogreen.com\/offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit\/\",\"name\":\"Offer and Onboarding: Payback for Building Strong Relationships as you Recruit - Castelo Green\",\"isPartOf\":{\"@id\":\"https:\/\/castelogreen.com\/pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/castelogreen.com\/offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/castelogreen.com\/offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/castelogreen.com\/wp-content\/uploads\/2024\/04\/onboarding-and-relationship-building.webp\",\"datePublished\":\"2024-04-10T15:51:16+00:00\",\"dateModified\":\"2024-04-10T16:21:52+00:00\",\"author\":{\"@id\":\"https:\/\/castelogreen.com\/pt\/#\/schema\/person\/b563c30cd4b274cb1a46d8e21945f3dd\"},\"description\":\"Offer and onboarding processes can further reinforce the relationship you build with new software engineering team members,\",\"breadcrumb\":{\"@id\":\"https:\/\/castelogreen.com\/offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/castelogreen.com\/offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/castelogreen.com\/offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit\/#primaryimage\",\"url\":\"https:\/\/castelogreen.com\/wp-content\/uploads\/2024\/04\/onboarding-and-relationship-building.webp\",\"contentUrl\":\"https:\/\/castelogreen.com\/wp-content\/uploads\/2024\/04\/onboarding-and-relationship-building.webp\",\"width\":1024,\"height\":1024,\"caption\":\"Onboarding new software engineer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/castelogreen.com\/offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/castelogreen.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Offer and Onboarding: Payback for Building Strong Relationships as you Recruit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/castelogreen.com\/pt\/#website\",\"url\":\"https:\/\/castelogreen.com\/pt\/\",\"name\":\"Castelo Green\",\"description\":\"Better Hiring, Stronger Teams\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/castelogreen.com\/pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/castelogreen.com\/pt\/#\/schema\/person\/b563c30cd4b274cb1a46d8e21945f3dd\",\"name\":\"Allen Shaw\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/castelogreen.com\/pt\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b2f4c8aaa1d33ef25bb42be4e5b94f78460d1d5c38ee766adbace83cf905c1f8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b2f4c8aaa1d33ef25bb42be4e5b94f78460d1d5c38ee766adbace83cf905c1f8?s=96&d=mm&r=g\",\"caption\":\"Allen Shaw\"},\"sameAs\":[\"https:\/\/castelogreen.com\"],\"url\":\"https:\/\/castelogreen.com\/pt\/author\/allen\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Offer and Onboarding: Payback for Building Strong Relationships as you Recruit - Castelo Green","description":"Offer and onboarding processes can further reinforce the relationship you build with new software engineering team members,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/castelogreen.com\/pt\/offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit\/","og_locale":"pt_PT","og_type":"article","og_title":"Offer and Onboarding: Payback for Building Strong Relationships as you Recruit - Castelo Green","og_description":"Offer and onboarding processes can further reinforce the relationship you build with new software engineering team members,","og_url":"https:\/\/castelogreen.com\/pt\/offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit\/","og_site_name":"Castelo Green","article_published_time":"2024-04-10T15:51:16+00:00","article_modified_time":"2024-04-10T16:21:52+00:00","og_image":[{"width":1024,"height":1024,"url":"http:\/\/castelogreen.com\/wp-content\/uploads\/2024\/04\/onboarding-and-relationship-building.webp","type":"image\/webp"}],"author":"Allen Shaw","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Allen Shaw","Tempo estimado de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/castelogreen.com\/offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit\/","url":"https:\/\/castelogreen.com\/offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit\/","name":"Offer and Onboarding: Payback for Building Strong Relationships as you Recruit - Castelo Green","isPartOf":{"@id":"https:\/\/castelogreen.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/castelogreen.com\/offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit\/#primaryimage"},"image":{"@id":"https:\/\/castelogreen.com\/offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit\/#primaryimage"},"thumbnailUrl":"https:\/\/castelogreen.com\/wp-content\/uploads\/2024\/04\/onboarding-and-relationship-building.webp","datePublished":"2024-04-10T15:51:16+00:00","dateModified":"2024-04-10T16:21:52+00:00","author":{"@id":"https:\/\/castelogreen.com\/pt\/#\/schema\/person\/b563c30cd4b274cb1a46d8e21945f3dd"},"description":"Offer and onboarding processes can further reinforce the relationship you build with new software engineering team members,","breadcrumb":{"@id":"https:\/\/castelogreen.com\/offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/castelogreen.com\/offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/castelogreen.com\/offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit\/#primaryimage","url":"https:\/\/castelogreen.com\/wp-content\/uploads\/2024\/04\/onboarding-and-relationship-building.webp","contentUrl":"https:\/\/castelogreen.com\/wp-content\/uploads\/2024\/04\/onboarding-and-relationship-building.webp","width":1024,"height":1024,"caption":"Onboarding new software engineer"},{"@type":"BreadcrumbList","@id":"https:\/\/castelogreen.com\/offer-and-onboarding-payback-for-building-strong-relationships-as-you-recruit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/castelogreen.com\/"},{"@type":"ListItem","position":2,"name":"Offer and Onboarding: Payback for Building Strong Relationships as you Recruit"}]},{"@type":"WebSite","@id":"https:\/\/castelogreen.com\/pt\/#website","url":"https:\/\/castelogreen.com\/pt\/","name":"Castelo Green","description":"Better Hiring, Stronger Teams","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/castelogreen.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/castelogreen.com\/pt\/#\/schema\/person\/b563c30cd4b274cb1a46d8e21945f3dd","name":"Allen Shaw","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/castelogreen.com\/pt\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b2f4c8aaa1d33ef25bb42be4e5b94f78460d1d5c38ee766adbace83cf905c1f8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b2f4c8aaa1d33ef25bb42be4e5b94f78460d1d5c38ee766adbace83cf905c1f8?s=96&d=mm&r=g","caption":"Allen Shaw"},"sameAs":["https:\/\/castelogreen.com"],"url":"https:\/\/castelogreen.com\/pt\/author\/allen\/"}]}},"_links":{"self":[{"href":"https:\/\/castelogreen.com\/pt\/wp-json\/wp\/v2\/posts\/863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/castelogreen.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/castelogreen.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/castelogreen.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/castelogreen.com\/pt\/wp-json\/wp\/v2\/comments?post=863"}],"version-history":[{"count":3,"href":"https:\/\/castelogreen.com\/pt\/wp-json\/wp\/v2\/posts\/863\/revisions"}],"predecessor-version":[{"id":867,"href":"https:\/\/castelogreen.com\/pt\/wp-json\/wp\/v2\/posts\/863\/revisions\/867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/castelogreen.com\/pt\/wp-json\/wp\/v2\/media\/864"}],"wp:attachment":[{"href":"https:\/\/castelogreen.com\/pt\/wp-json\/wp\/v2\/media?parent=863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/castelogreen.com\/pt\/wp-json\/wp\/v2\/categories?post=863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/castelogreen.com\/pt\/wp-json\/wp\/v2\/tags?post=863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}